{"id":3390,"date":"2019-12-04T15:58:53","date_gmt":"2019-12-04T14:58:53","guid":{"rendered":"https:\/\/lexgoapp.com\/blog\/?p=3390"},"modified":"2023-04-16T23:59:07","modified_gmt":"2023-04-16T21:59:07","slug":"profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal","status":"publish","type":"post","link":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/","title":{"rendered":"Profesionales y abogados del sector inmobiliario analizan la llegada de herramientas tecnol\u00f3gicas y su marco legal"},"content":{"rendered":"<h3>El concepto de Proptech define el desarrollo de herramientas tecnol\u00f3gicas en esta actividad econ\u00f3mica<\/h3>\n<p>La tecnolog\u00eda ha irrumpido tambi\u00e9n en el sector inmobiliaro. Hace unos d\u00edas tuvo lugar un nuevo \u201cmeetup\u201d de los Legal Hackers de Madrid. El encuentro se desarroll\u00f3 en el centro de innovaci\u00f3n y ecosistema tecnol\u00f3gico <a href=\"https:\/\/gomadrid.tech\/es\/home-es\/\">GoMadrid<\/a> en la madrile\u00f1a calle de Gran V\u00eda. Bajo el t\u00edtulo \u201cProptech: Real Estate, Real Challenge!\u201d se debati\u00f3 sobre el desarrollo de soluciones y proyectos derivados de la fusi\u00f3n entre el derecho y la innovaci\u00f3n tecnol\u00f3gica para el sector tradicional inmobiliario.<\/p>\n<p>Madrid Legal Hackers es una comunidad descentralizada de cultura abierta y compuesta por profesionales abogados, tecn\u00f3logos, consultores, marketeros, docentes y estudiantes unidos por una misma voluntad de explorar y descubrir las soluciones a la hora de conjugar el derecho y la tecnolog\u00eda. Para ello organizan eventos y encuentros en los que se abordan temas de tecnolog\u00eda y legaltech.<\/p>\n<p>El movimiento Legal Hackers naci\u00f3 en EEUU a finales del 2011 y desde entonces no ha parado de crecer. Actualmente cuenta con 150 cap\u00edtulos y est\u00e1 presente en numerosos pa\u00edses y ciudades de los seis continentes: <a href=\"http:\/\/www.legalhackers.org\">www.legalhackers.org<\/a><\/p>\n<p>En Espa\u00f1a est\u00e1 presente en varias ciudades como Barcelona. Bilbao, Valencia, etc. La comunidad Legal Hackers en Madrid cuenta con una comunidad de m\u00e1s de 2200 personas y se cre\u00f3 en 2015.<\/p>\n<p>Esta jornada de trabajo \u00a0fue moderado por <strong>Guillermo P\u00e9rez Alonso<\/strong>, coorganizador de estos eventos en Madrid y socio director de Social Lex. Cont\u00f3 \u00a0con la participaci\u00f3n tanto de profesionales del sector inmobiliario como de abogados expertos en urbanismo e inmobiliario.<\/p>\n<p>As\u00ed, <strong>Silvia Mendoza<\/strong>, Responsable de Experiencia de Cliente, Innovaci\u00f3n &amp; Marketing del Grupo Inmobiliario Metrovacesa, cont\u00f3 como la compa\u00f1\u00eda est\u00e1 adaptando su modelo de negocio a trav\u00e9s de distintas iniciativas con la que est\u00e1n involucrando a todos los departamentos de la compa\u00f1\u00eda, dejando entrar a trav\u00e9s de nuevas alianzas start-ups y equipos de profesionales externos, con nuevos servicios y herramientas muy enfocadas al negocio y el cliente final.<\/p>\n<p>Seg\u00fan Silvia, \u201cnuestra forma de trabajo est\u00e1 cambiando al conseguir de nuestros proyectos un producto m\u00ednimo viable de manera r\u00e1pida. Esto nos obliga a ser mucho m\u00e1s colaborativos en entre nosotros, incluidos los equipos legales, en los que hay much\u00edsima retroalimentaci\u00f3n entre todos\u201d. Comentaba Mendoza que \u201cHe podido saber de cuestiones legales espec\u00edficas de cada proyecto, y esa informaci\u00f3n es tan valiosa como la de otras \u00e1reas de producci\u00f3n.\u201d<\/p>\n<p>La responsable de innovaci\u00f3n de la cotizada en el IBEX, cont\u00f3 c\u00f3mo, adem\u00e1s de estar usando para sus proyectos tecnolog\u00edas como la realidad aumentada para la venta a distancia, dom\u00f3tica o IOT en sus productos, han encontrado en la tecnolog\u00eda Blockchain nuevas formas de aportar nuevo valor al sector, <em>tokenizando<\/em> propiedades para la administraci\u00f3n y registro de las mismas \u201cdesde el momento que nace cada proyecto\u201d.<\/p>\n<p>Por su parte, <strong>Juan Carlos Rivera<\/strong>, Training &amp; Consulting Manager en Adevinta, compa\u00f1\u00eda de tecnolog\u00eda desde donde dirige los equipos de consultor\u00eda de portales como Fotocasa o Habitaclia, explic\u00f3 el modelo de negocio de los marketplaces inmobiliarios y puso el acento en el mercado dom\u00e9stico, donde \u201cel potencial del mercado espa\u00f1ol es muy bueno, somos referencia en muchas de las facetas del proptech, y muchos pa\u00edses se est\u00e1n fijando en nosotros\u201d.<\/p>\n<p>Para Rivera, que tambi\u00e9n es profesor de marketing en programas internacionales relacionados con urbanismo e inmobiliario, estamos inmersos en una transformaci\u00f3n global, pero no s\u00f3lo tecnol\u00f3gica sino tambi\u00e9n de paradigmas, cultura y procesos, donde la clave no est\u00e1 en implementar tecnolog\u00eda, sino en trabajar para transformar la cultura empresarial.<\/p>\n<p>En el modelo de plataformas como Fotocasa, la implementaci\u00f3n de procesos mucho m\u00e1s eficientes ayuda a automatizar procesos y dotar de inteligencia las decisiones. Para Rivera \u201ces en la explotaci\u00f3n de los datos donde hay que poner el foco para tomar minimizar la incertidumbre y los riesgos en la necesidad de tomar decisiones m\u00e1s r\u00e1pidas\u201d.<\/p>\n<p><strong>\u00a0<\/strong>En este meetup fue <strong>Mercedes de Parada<\/strong>, abogada y Socia Fundadora de Letradox, firma especializada, entre otras materias, en derecho inmobiliario y urbanismo, la que arroj\u00f3 luz sobre la seguridad y regulaci\u00f3n en el \u00e1mbito jur\u00eddico del proptech.<\/p>\n<p>Para de Parada \u201cAl igual que en el sector financiero con la Fintech, el inmobiliario est\u00e1 siendo colonizado por nuevas empresas cuyo objetivo es innovar y simplificar el negocio a trav\u00e9s de herramientas tecnol\u00f3gicas, y nuestra aportaci\u00f3n como abogados para estar a la altura del desarrollo de este mercado, como cualquier otro, es dejar atr\u00e1s procesos legales anal\u00f3gicos y llevarlos al mundo actual, el digital\u201d.<\/p>\n<p>Dentro del derecho inmobiliario, se encuentran multitud de elementos como pueden ser por ejemplo los contratos de arras, compraventa, arrendamientos, derechos reales etc., a la par que licencias en el urbanismo a los que se les podr\u00eda dar un valor a\u00f1adido con tecnolog\u00eda como el blockchain, en lo que los notarios, lejos de desaparecer, \u201cporque seguir\u00e1 siendo necesaria su capacidad federataria\u201d, ya est\u00e1n trabajando.<\/p>\n<p>Para la abogada, el futuro del proptech, como en tantos otros sectores, ser\u00e1 desarrollar una customizaci\u00f3n masiva de los servicios, es decir, adaptarse de forma personalizada a las necesidades de cada usuario o cliente.<\/p>\n<p><strong><em>Por\u00a0<a href=\"https:\/\/twitter.com\/luisjasanchez?lang=es\">@LuisjaSanchez<\/a>, Periodista Jur\u00eddico<\/em><\/strong>.<\/p>\n<p>Si necesita los servicios de un abogado\u00a0<a href=\"https:\/\/lexgoapp.com\/abogados-inmobiliario\">especialista en derecho inmobiliario<\/a>, no duda en consultar nuestro\u00a0<a href=\"https:\/\/lexgoapp.com\/abogados-inmobiliario\">amplio directorio de abogados especialistas<\/a>\u00a0y visitar nuestra p\u00e1gina web.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concepto de Proptech define el desarrollo de herramientas tecnol\u00f3gicas en esta actividad econ\u00f3mica La tecnolog\u00eda ha irrumpido tambi\u00e9n en el sector inmobiliaro. Hace unos d\u00edas\u2026<\/p>\n","protected":false},"author":5,"featured_media":3391,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,145],"tags":[485,677,380,72,676],"class_list":["post-3390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario","category-nuevas-tecnologias","tag-abogado-inmobiliario","tag-derecho-inmobiliario","tag-inmobiliario","tag-legaltech","tag-proptech"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Profesionales y abogados del sector inmobiliario analizan la llegada de herramientas tecnol\u00f3gicas y su marco legal - LexGoApp Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profesionales y abogados del sector inmobiliario analizan la llegada de herramientas tecnol\u00f3gicas y su marco legal - LexGoApp Blog\" \/>\n<meta property=\"og:description\" content=\"El concepto de Proptech define el desarrollo de herramientas tecnol\u00f3gicas en esta actividad econ\u00f3mica La tecnolog\u00eda ha irrumpido tambi\u00e9n en el sector inmobiliaro. Hace unos d\u00edas\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"LexGoApp Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61573073231370\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-04T14:58:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-16T21:59:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/12\/foto_proptech.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4032\" \/>\n\t<meta property=\"og:image:height\" content=\"3024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LexGoApp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lexgoapp\" \/>\n<meta name=\"twitter:site\" content=\"@lexgoapp\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"LexGoApp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/\"},\"author\":{\"name\":\"LexGoApp\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#\\\/schema\\\/person\\\/e043f73033686ba8643a6a11278153ab\"},\"headline\":\"Profesionales y abogados del sector inmobiliario analizan la llegada de herramientas tecnol\u00f3gicas y su marco legal\",\"datePublished\":\"2019-12-04T14:58:53+00:00\",\"dateModified\":\"2023-04-16T21:59:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/\"},\"wordCount\":957,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/foto_proptech.jpg\",\"keywords\":[\"Abogado inmobiliario\",\"derecho inmobiliario\",\"inmobiliario\",\"Legaltech\",\"proptech\"],\"articleSection\":[\"INMOBILIARIO\",\"NUEVAS TECNOLOG\u00cdAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/\",\"url\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/\",\"name\":\"Profesionales y abogados del sector inmobiliario analizan la llegada de herramientas tecnol\u00f3gicas y su marco legal - LexGoApp Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/foto_proptech.jpg\",\"datePublished\":\"2019-12-04T14:58:53+00:00\",\"dateModified\":\"2023-04-16T21:59:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/foto_proptech.jpg\",\"contentUrl\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/foto_proptech.jpg\",\"width\":4032,\"height\":3024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profesionales y abogados del sector inmobiliario analizan la llegada de herramientas tecnol\u00f3gicas y su marco legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/\",\"name\":\"LexGoApp Blog\",\"description\":\"LexGo App, la primera app para encontrar abogados especializados en tu zona.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#organization\",\"name\":\"LEXGOApp\",\"url\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/logo-2.png\",\"width\":664,\"height\":165,\"caption\":\"LEXGOApp\"},\"image\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61573073231370\",\"https:\\\/\\\/x.com\\\/lexgoapp\",\"https:\\\/\\\/www.instagram.com\\\/lexgoapp\\\/?hl=es\",\"http:\\\/\\\/linkedin.com\\\/company\\\/lexgoapp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbbDsdaJf_aDhjnvi8xPQkg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#\\\/schema\\\/person\\\/e043f73033686ba8643a6a11278153ab\",\"name\":\"LexGoApp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g\",\"caption\":\"LexGoApp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Profesionales y abogados del sector inmobiliario analizan la llegada de herramientas tecnol\u00f3gicas y su marco legal - LexGoApp Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/","og_locale":"es_ES","og_type":"article","og_title":"Profesionales y abogados del sector inmobiliario analizan la llegada de herramientas tecnol\u00f3gicas y su marco legal - LexGoApp Blog","og_description":"El concepto de Proptech define el desarrollo de herramientas tecnol\u00f3gicas en esta actividad econ\u00f3mica La tecnolog\u00eda ha irrumpido tambi\u00e9n en el sector inmobiliaro. Hace unos d\u00edas\u2026","og_url":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/","og_site_name":"LexGoApp Blog","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61573073231370","article_published_time":"2019-12-04T14:58:53+00:00","article_modified_time":"2023-04-16T21:59:07+00:00","og_image":[{"width":4032,"height":3024,"url":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/12\/foto_proptech.jpg","type":"image\/jpeg"}],"author":"LexGoApp","twitter_card":"summary_large_image","twitter_creator":"@lexgoapp","twitter_site":"@lexgoapp","twitter_misc":{"Escrito por":"LexGoApp","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/#article","isPartOf":{"@id":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/"},"author":{"name":"LexGoApp","@id":"https:\/\/lexgoapp.com\/blog\/#\/schema\/person\/e043f73033686ba8643a6a11278153ab"},"headline":"Profesionales y abogados del sector inmobiliario analizan la llegada de herramientas tecnol\u00f3gicas y su marco legal","datePublished":"2019-12-04T14:58:53+00:00","dateModified":"2023-04-16T21:59:07+00:00","mainEntityOfPage":{"@id":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/"},"wordCount":957,"commentCount":1,"publisher":{"@id":"https:\/\/lexgoapp.com\/blog\/#organization"},"image":{"@id":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/#primaryimage"},"thumbnailUrl":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/12\/foto_proptech.jpg","keywords":["Abogado inmobiliario","derecho inmobiliario","inmobiliario","Legaltech","proptech"],"articleSection":["INMOBILIARIO","NUEVAS TECNOLOG\u00cdAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/","url":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/","name":"Profesionales y abogados del sector inmobiliario analizan la llegada de herramientas tecnol\u00f3gicas y su marco legal - LexGoApp Blog","isPartOf":{"@id":"https:\/\/lexgoapp.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/#primaryimage"},"image":{"@id":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/#primaryimage"},"thumbnailUrl":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/12\/foto_proptech.jpg","datePublished":"2019-12-04T14:58:53+00:00","dateModified":"2023-04-16T21:59:07+00:00","breadcrumb":{"@id":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/#primaryimage","url":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/12\/foto_proptech.jpg","contentUrl":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/12\/foto_proptech.jpg","width":4032,"height":3024},{"@type":"BreadcrumbList","@id":"https:\/\/lexgoapp.com\/blog\/profesionales-y-abogados-del-sector-inmobiliario-analizan-la-llegada-de-herramientas-tecnologicas-y-su-marco-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lexgoapp.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Profesionales y abogados del sector inmobiliario analizan la llegada de herramientas tecnol\u00f3gicas y su marco legal"}]},{"@type":"WebSite","@id":"https:\/\/lexgoapp.com\/blog\/#website","url":"https:\/\/lexgoapp.com\/blog\/","name":"LexGoApp Blog","description":"LexGo App, la primera app para encontrar abogados especializados en tu zona.","publisher":{"@id":"https:\/\/lexgoapp.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lexgoapp.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lexgoapp.com\/blog\/#organization","name":"LEXGOApp","url":"https:\/\/lexgoapp.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lexgoapp.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2026\/07\/logo-2.png","contentUrl":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2026\/07\/logo-2.png","width":664,"height":165,"caption":"LEXGOApp"},"image":{"@id":"https:\/\/lexgoapp.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61573073231370","https:\/\/x.com\/lexgoapp","https:\/\/www.instagram.com\/lexgoapp\/?hl=es","http:\/\/linkedin.com\/company\/lexgoapp","https:\/\/www.youtube.com\/channel\/UCbbDsdaJf_aDhjnvi8xPQkg"]},{"@type":"Person","@id":"https:\/\/lexgoapp.com\/blog\/#\/schema\/person\/e043f73033686ba8643a6a11278153ab","name":"LexGoApp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g","caption":"LexGoApp"}}]}},"_links":{"self":[{"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/posts\/3390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/comments?post=3390"}],"version-history":[{"count":2,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/posts\/3390\/revisions"}],"predecessor-version":[{"id":6990,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/posts\/3390\/revisions\/6990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/media\/3391"}],"wp:attachment":[{"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/media?parent=3390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/categories?post=3390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/tags?post=3390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}