{"id":3247,"date":"2019-10-15T14:59:26","date_gmt":"2019-10-15T12:59:26","guid":{"rendered":"https:\/\/lexgoapp.com\/blog\/?p=3247"},"modified":"2019-10-15T14:59:26","modified_gmt":"2019-10-15T12:59:26","slug":"cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores","status":"publish","type":"post","link":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/","title":{"rendered":"Cesiones de cr\u00e9ditos y derecho de retracto de los deudores"},"content":{"rendered":"<h3><strong>El Derecho de retracto en la cesi\u00f3n de cr\u00e9ditos<\/strong><strong>\u00a0<\/strong><\/h3>\n<p><strong>\u00a0<\/strong>La crisis econ\u00f3mica en nuestro pa\u00eds gener\u00f3 un <strong>aumento de cr\u00e9ditos en situaci\u00f3n de impago<\/strong>, situaci\u00f3n que afect\u00f3 directamente a las entidades bancarias que se encontraron con un <strong>importante incremento de morosidad<\/strong>. \u00c9stas, para mejorar sus resultados econ\u00f3micos y cumplir con las exigencias contables, vendieron una parte importante de estos cr\u00e9ditos, tanto hipotecarios como personales, a otras entidades; adquiriendo en los \u00faltimos a\u00f1os un protagonismo considerable este tipo de operaciones.<\/p>\n<p>Los adquirentes de estos cr\u00e9ditos, normalmente fondos de inversi\u00f3n, adquir\u00edan los cr\u00e9ditos a un bajo coste, logrando as\u00ed una gran rentabilidad.<\/p>\n<p>Si bien la cesi\u00f3n de cr\u00e9ditos es una pr\u00e1ctica legal, s\u00ed que es verdad que <strong>suscita diversos problemas a los deudores<\/strong>, entre ellos la falta de informaci\u00f3n de quien es su nuevo acreedor y\u00a0 la posibilidad de re negociar unas mayores facilidades en el pago de la deuda.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>El Derecho de retracto en la cesi\u00f3n de cr\u00e9ditos<\/strong><\/h3>\n<p>En la compraventa de cr\u00e9ditos impagados por parte de las entidades bancarias entra en juego el <strong>\u201cretracto de cr\u00e9dito litigioso\u201d<\/strong>, un derecho reconocido al deudor en el art\u00edculo 1535 del C\u00f3digo Civil que se refiere a este de la siguiente manera:<\/p>\n<p><em>Vendi\u00e9ndose un cr\u00e9dito litigioso, el deudor tendr\u00e1 derecho a extinguirlo, reembolsando al cesionario el precio que pag\u00f3, las costas que se le hubiesen ocasionado y los intereses del precio desde el d\u00eda en que \u00e9ste fue satisfecho.<\/em><\/p>\n<p>En suma, entendemos el derecho de retracto de un cr\u00e9dito litigioso como la <strong>facultad concedida al deudor para exigir su cr\u00e9dito<\/strong>, bajo el cumplimento de determinados requisitos que veremos a continuaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Requisitos necesarios para el ejercicio del derecho de retracto en la cesi\u00f3n de cr\u00e9ditos<\/strong><\/h3>\n<p><strong>\u00a0<\/strong>En la pr\u00e1ctica, no siempre que se produce la venta de un cr\u00e9dito el deudor podr\u00e1 pretender la extinci\u00f3n del mismo. En este sentido, tanto la legislaci\u00f3n como la jurisprudencia han establecido una serie de <strong>supuestos que deben cumplirse <\/strong>para que pueda hacerse efectivo el ejercicio del retracto:<\/p>\n<ol>\n<li>Que exista la venta o transmisi\u00f3n de un cr\u00e9dito<\/li>\n<li>Que el cr\u00e9dito tenga la consideraci\u00f3n de litigioso<\/li>\n<li>Que la acci\u00f3n de retracto se ejerza en el plazo de nueve d\u00edas<\/li>\n<li>Que se proceda al pago o consignaci\u00f3n de las cantidades por las que se cedi\u00f3 el cr\u00e9dito<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li>\n<h3><strong> Que exista venta o transmisi\u00f3n de un cr\u00e9dito<\/strong><\/h3>\n<\/li>\n<\/ol>\n<p>En primer lugar, hay que determinar qu\u00e9 se entiende por<strong> \u201ccr\u00e9dito\u201d<\/strong>. El Tribunal Supremo en su Sentencia 976\/2008 de 31 de octubre de 2008 considera que debe entenderse en un sentido amplio como<strong> \u201ctodo derecho individualizado transmisible<\/strong>\u201d.<\/p>\n<p>En cuanto a la <strong>venta o transmisi\u00f3n<\/strong>, no existe unanimidad. Ya que parte de la doctrina sostiene que en el caso de que se produzca una transmisi\u00f3n de una masa o pluralidad de cr\u00e9ditos por un precio conjunto (ser\u00eda el caso del que habl\u00e1bamos al inicio de las entidades bancarias) no podr\u00eda considerarse como contratos individualizados, sino como un conjunto, por lo que no cabr\u00eda el ejercicio del retracto <em>(en este sentido, la SAP de Madrid, de 7 de octubre de 2002).<\/em><\/p>\n<p>&nbsp;<\/p>\n<ol start=\"2\">\n<li>\n<h3><strong> Que el cr\u00e9dito tenga la consideraci\u00f3n de litigioso<\/strong><\/h3>\n<\/li>\n<\/ol>\n<p>Seg\u00fan el Tribunal Supremo, la \u201clitigiosidad\u201d comienza en el momento de <strong>contestaci\u00f3n de la demanda<\/strong>, y siempre que exista una oposici\u00f3n. Se entiende por oposici\u00f3n la contestaci\u00f3n del deudor a la demanda o, eventualmente, una oposici\u00f3n t\u00e1cita como ser\u00eda la rebeld\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"3\">\n<li>\n<h3><strong> Que la acci\u00f3n de retracto se ejerza en el plazo de nueve d\u00edas<\/strong><\/h3>\n<\/li>\n<\/ol>\n<p>Tal y como establece el C\u00f3digo Civil, la acci\u00f3n de retracto debe de ejercerse dentro del plazo de 9 d\u00edas, <strong>empezando a contar el plazo<\/strong> desde el momento en el que <strong>el nuevo acreedor<\/strong>, o cesionario, <strong>reclama el pago de la deuda<\/strong> y el deudor conoce todos los extremos que precisa saber para ejercer su derecho: el precio, los intereses, costas y dem\u00e1s gastos soportados por el acreedor o cesionario.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"4\">\n<li>\n<h3><strong> Que se proceda al pago o consignaci\u00f3n de las cantidades por las que se cedi\u00f3 el cr\u00e9dito<\/strong><\/h3>\n<\/li>\n<\/ol>\n<p><em>\u00a0<\/em>Si bien este no es un requisito puramente \u201clegal\u201d s\u00ed que podr\u00edamos considerarlo un requisito procesal, ya que el <strong>art\u00edculo 266.3 de Ley de Enjuiciamiento Civil<\/strong> solicita, entre los documentos exigidos para la presentaci\u00f3n correcta de la demanda:<\/p>\n<p>\u201cLos documentos que constituyan un principio de prueba del t\u00edtulo en que se funden las demandas de retracto y, cuando la consignaci\u00f3n del precio se exija por ley o por contrato, el documento que acredite haber consignado, si fuere conocido, el precio de la cosa objeto de retracto o haberse constituido cauci\u00f3n que garantice la consignaci\u00f3n en cuanto el precio se conociere\u201d<\/p>\n<p><em>\u00a0<\/em>La consignaci\u00f3n es un requisito procesal para evitar que qui\u00e9n no tenga capacidad econ\u00f3mica suficiente para ejercer el retracto pueda hacer valer este derecho. En cuanto a la <strong>cuant\u00eda de la consignaci\u00f3n<\/strong>, esta ser\u00e1 el resultado de la suma del precio de la transmisi\u00f3n del cr\u00e9dito m\u00e1s los intereses legales del mismo desde la fecha de transacci\u00f3n seg\u00fan la jurisprudencia.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Cesi\u00f3n de cr\u00e9ditos en masa<\/strong><\/h3>\n<p><strong>\u00a0<\/strong>En resumen, el deudor podr\u00e1 ejercer su <strong>derecho de retracto en la cesi\u00f3n de su cr\u00e9dito<\/strong> siempre y cuando: se trate de un <strong>cr\u00e9dito litigioso<\/strong>, se ejercite la acci\u00f3n dentro del plazo de <strong>nueve d\u00edas<\/strong> que establece el C\u00f3digo Civil (una vez conocidos los extremos en que se ha realizado la cesi\u00f3n) y siempre que el <strong>precio de dicho cr\u00e9dito est\u00e9 individualizado<\/strong>.<\/p>\n<p>En relaci\u00f3n a este \u00faltimo punto, existe una gran pol\u00e9mica en los supuestos en los que se produzca una <strong>venta en masa de cr\u00e9ditos<\/strong> cuyo precio no est\u00e9 individualizado, como ser\u00eda el caso de la venta de cr\u00e9ditos, tanto hipotecarios como personales, por parte de entidades bancarias a fondos de inversi\u00f3n.<\/p>\n<p>Como ve\u00edamos, el derecho de retracto en la cesi\u00f3n de un cr\u00e9dito litigioso, seg\u00fan la redacci\u00f3n del C\u00f3digo Civil, parece perfectamente ajustable a<strong> situaciones en las que exista un \u00fanico cr\u00e9dito litigioso como objeto de la cesi\u00f3n<\/strong>. No resulta tan sencillo en el caso de una <strong>transmisi\u00f3n en masa, cuando los cr\u00e9ditos no son susceptibles de ser individualizados<\/strong> y existe una indeterminaci\u00f3n del precio de adquisici\u00f3n del cr\u00e9dito que hace que se contemple como una cesi\u00f3n global de cr\u00e9ditos, no individualizada.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Derecho de retracto en la cesi\u00f3n de cr\u00e9ditos\u00a0 \u00a0La crisis econ\u00f3mica en nuestro pa\u00eds gener\u00f3 un aumento de cr\u00e9ditos en situaci\u00f3n de impago, situaci\u00f3n que\u2026<\/p>\n","protected":false},"author":5,"featured_media":3248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[635,68,632,633,112,634,631],"class_list":["post-3247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-civil","tag-cesion-de-credito","tag-civil","tag-creditos-en-masa","tag-derecho-de-retracto","tag-deuda","tag-litigio","tag-retracto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cesiones de cr\u00e9ditos y derecho de retracto de los deudores - LexGoApp Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cesiones de cr\u00e9ditos y derecho de retracto de los deudores - LexGoApp Blog\" \/>\n<meta property=\"og:description\" content=\"El Derecho de retracto en la cesi\u00f3n de cr\u00e9ditos\u00a0 \u00a0La crisis econ\u00f3mica en nuestro pa\u00eds gener\u00f3 un aumento de cr\u00e9ditos en situaci\u00f3n de impago, situaci\u00f3n que\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/\" \/>\n<meta property=\"og:site_name\" content=\"LexGoApp Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61573073231370\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-15T12:59:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/09\/bank-bank-notes-banking-259249-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LexGoApp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lexgoapp\" \/>\n<meta name=\"twitter:site\" content=\"@lexgoapp\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"LexGoApp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/\"},\"author\":{\"name\":\"LexGoApp\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#\\\/schema\\\/person\\\/e043f73033686ba8643a6a11278153ab\"},\"headline\":\"Cesiones de cr\u00e9ditos y derecho de retracto de los deudores\",\"datePublished\":\"2019-10-15T12:59:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/\"},\"wordCount\":1143,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/bank-bank-notes-banking-259249.jpg\",\"keywords\":[\"cesion de credito\",\"civil\",\"creditos en masa\",\"derecho de retracto\",\"Deuda\",\"litigio\",\"retracto\"],\"articleSection\":[\"CIVIL\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/\",\"url\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/\",\"name\":\"Cesiones de cr\u00e9ditos y derecho de retracto de los deudores - LexGoApp Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/bank-bank-notes-banking-259249.jpg\",\"datePublished\":\"2019-10-15T12:59:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/bank-bank-notes-banking-259249.jpg\",\"contentUrl\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/bank-bank-notes-banking-259249.jpg\",\"width\":5472,\"height\":3648},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cesiones de cr\u00e9ditos y derecho de retracto de los deudores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/\",\"name\":\"LexGoApp Blog\",\"description\":\"LexGo App, la primera app para encontrar abogados especializados en tu zona.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#organization\",\"name\":\"LEXGOApp\",\"url\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/logo-2.png\",\"width\":664,\"height\":165,\"caption\":\"LEXGOApp\"},\"image\":{\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61573073231370\",\"https:\\\/\\\/x.com\\\/lexgoapp\",\"https:\\\/\\\/www.instagram.com\\\/lexgoapp\\\/?hl=es\",\"http:\\\/\\\/linkedin.com\\\/company\\\/lexgoapp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbbDsdaJf_aDhjnvi8xPQkg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lexgoapp.com\\\/blog\\\/#\\\/schema\\\/person\\\/e043f73033686ba8643a6a11278153ab\",\"name\":\"LexGoApp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g\",\"caption\":\"LexGoApp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cesiones de cr\u00e9ditos y derecho de retracto de los deudores - LexGoApp Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/","og_locale":"es_ES","og_type":"article","og_title":"Cesiones de cr\u00e9ditos y derecho de retracto de los deudores - LexGoApp Blog","og_description":"El Derecho de retracto en la cesi\u00f3n de cr\u00e9ditos\u00a0 \u00a0La crisis econ\u00f3mica en nuestro pa\u00eds gener\u00f3 un aumento de cr\u00e9ditos en situaci\u00f3n de impago, situaci\u00f3n que\u2026","og_url":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/","og_site_name":"LexGoApp Blog","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61573073231370","article_published_time":"2019-10-15T12:59:26+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/09\/bank-bank-notes-banking-259249-1024x683.jpg","type":"image\/jpeg"}],"author":"LexGoApp","twitter_card":"summary_large_image","twitter_creator":"@lexgoapp","twitter_site":"@lexgoapp","twitter_misc":{"Escrito por":"LexGoApp","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/#article","isPartOf":{"@id":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/"},"author":{"name":"LexGoApp","@id":"https:\/\/lexgoapp.com\/blog\/#\/schema\/person\/e043f73033686ba8643a6a11278153ab"},"headline":"Cesiones de cr\u00e9ditos y derecho de retracto de los deudores","datePublished":"2019-10-15T12:59:26+00:00","mainEntityOfPage":{"@id":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/"},"wordCount":1143,"commentCount":0,"publisher":{"@id":"https:\/\/lexgoapp.com\/blog\/#organization"},"image":{"@id":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/#primaryimage"},"thumbnailUrl":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/09\/bank-bank-notes-banking-259249.jpg","keywords":["cesion de credito","civil","creditos en masa","derecho de retracto","Deuda","litigio","retracto"],"articleSection":["CIVIL"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/","url":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/","name":"Cesiones de cr\u00e9ditos y derecho de retracto de los deudores - LexGoApp Blog","isPartOf":{"@id":"https:\/\/lexgoapp.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/#primaryimage"},"image":{"@id":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/#primaryimage"},"thumbnailUrl":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/09\/bank-bank-notes-banking-259249.jpg","datePublished":"2019-10-15T12:59:26+00:00","breadcrumb":{"@id":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/#primaryimage","url":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/09\/bank-bank-notes-banking-259249.jpg","contentUrl":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2019\/09\/bank-bank-notes-banking-259249.jpg","width":5472,"height":3648},{"@type":"BreadcrumbList","@id":"https:\/\/lexgoapp.com\/blog\/cesiones-de-creditos-y-derecho-de-retracto-de-los-deudores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lexgoapp.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Cesiones de cr\u00e9ditos y derecho de retracto de los deudores"}]},{"@type":"WebSite","@id":"https:\/\/lexgoapp.com\/blog\/#website","url":"https:\/\/lexgoapp.com\/blog\/","name":"LexGoApp Blog","description":"LexGo App, la primera app para encontrar abogados especializados en tu zona.","publisher":{"@id":"https:\/\/lexgoapp.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lexgoapp.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lexgoapp.com\/blog\/#organization","name":"LEXGOApp","url":"https:\/\/lexgoapp.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lexgoapp.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2026\/07\/logo-2.png","contentUrl":"https:\/\/lexgoapp.com\/blog\/wp-content\/uploads\/2026\/07\/logo-2.png","width":664,"height":165,"caption":"LEXGOApp"},"image":{"@id":"https:\/\/lexgoapp.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61573073231370","https:\/\/x.com\/lexgoapp","https:\/\/www.instagram.com\/lexgoapp\/?hl=es","http:\/\/linkedin.com\/company\/lexgoapp","https:\/\/www.youtube.com\/channel\/UCbbDsdaJf_aDhjnvi8xPQkg"]},{"@type":"Person","@id":"https:\/\/lexgoapp.com\/blog\/#\/schema\/person\/e043f73033686ba8643a6a11278153ab","name":"LexGoApp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ba8e4cef8c1864294dd66fc75409a92fc1796419c840989371d1deb11729849?s=96&d=mm&r=g","caption":"LexGoApp"}}]}},"_links":{"self":[{"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/posts\/3247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/comments?post=3247"}],"version-history":[{"count":1,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/posts\/3247\/revisions"}],"predecessor-version":[{"id":3249,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/posts\/3247\/revisions\/3249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/media\/3248"}],"wp:attachment":[{"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/media?parent=3247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/categories?post=3247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lexgoapp.com\/blog\/wp-json\/wp\/v2\/tags?post=3247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}